{"id":2943,"date":"2023-04-18T21:02:06","date_gmt":"2023-04-18T19:02:06","guid":{"rendered":"https:\/\/barlees.eu\/produkt\/tsampa-original-bio-250g-650g\/"},"modified":"2026-06-21T19:07:08","modified_gmt":"2026-06-21T17:07:08","slug":"tsampa-original-bio-250g-650g","status":"publish","type":"product","link":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/","title":{"rendered":"TSAMPA ORIGINAL BIO 250g, 650G"},"content":{"rendered":"<p>Rezepte und Zubereitung:<br \/>\n Tsampa kann man auf vielf\u00e4ltige Weise genie\u00dfen. Es eignet sich jedoch besonders gut als <strong>schnelles und herzhaftes Fr\u00fchst\u00fcck oder als Snack <\/strong>. <strong>NICHT INSTANT-FORM!<\/strong> Es wird nur fein gemahlen, um alle N\u00e4hrstoffe zu erhalten. Tsampa kann aber auch f\u00fcr andere erstaunliche herzhafte und s\u00fc\u00dfe Gerichte verwendet werden. Es kann Smoothies oder Joghurt zugesetzt werden. <strong>Rezepte f\u00fcr TSAMPA finden Sie <a href=\"https:\/\/barlees.eu\/de\/Ingredience\/tsampa-de\/\">HIER<\/a>.<\/strong><\/p>\n<p><strong>Barlee&#8217;s Tsampa Original enth\u00e4lt:<\/strong><\/p>\n<p><strong>Kohlenhydrate<\/strong>: Tsampa ist eine gute Quelle aus komplexen Kohlenhydraten, die den K\u00f6rper f\u00fcr verschiedene k\u00f6rperliche Aktivit\u00e4ten mit Energie versorgen.. Eiwei\u00df: Tsampa hat einen relativ hohen Eiwei\u00dfgehalt, der f\u00fcr den Aufbau und die Reparatur von Geweben sowie zur Unterst\u00fctzung verschiedener K\u00f6rperfunktionen unerl\u00e4sslich ist.<\/p>\n<p><strong>Beta-Glucane<\/strong>: Tsampa ist eine gute Quelle f\u00fcr Beta-Glucane. BETA-GLUCANE dienen zur Aufrechterhaltung des normalen Cholesterinspiegels im Blut\u201c, \u201eDer Verzehr von Beta- Glucan aus Gerste als Bestandteil der Nahrung schr\u00e4nkt den Anstieg des Blutzuckerspiegels nach dieser Mahlzeit ein\u201c Anerkannter Gesundheitsanspruch.<\/p>\n<p><strong>Vitamine<\/strong>: Tsampa enth\u00e4lt mehrere Vitamine, darunter B-Vitamine wie Thiamin (B1), Riboflavin (B2), Niacin (B3) und Vitamin B6. Mineralien: Tsampa ist reich an Mineralien wie Phosphor, Magnesium und Zink. Tsampa ist auch eine gute Quelle f\u00fcr Antioxidantien.<\/p>\n<p><strong>Fett<\/strong>: Tsampa enth\u00e4lt relativ wenig Fett und ist daher eine gute Wahl f\u00fcr diejenigen, die auf ihre Fettaufnahme achten.<\/p>\n<p><strong>Zutaten<\/strong>: Gemahlene ger\u00f6stete Vollkorngerste aus biologischem Anbau.<br \/>\n<strong>Gesamtgewicht<\/strong>: 250 g \/ Mindesthaltbarkeit: am oberen Ende der Verpackung. \/ An einem trockenen Ort aufbewahren.<br \/>\n<strong>Hersteller<\/strong>: Orzo coffee s.r.o., Hodkovick\u00e1 109, 463 12 Liberec \/ Made in Czech Republic.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barlee&#8217;s bringt Ihnen die m\u00e4chtige Kraft von Tsampa. Tsampa ist ein traditionelles tibetisches Essen, bei uns hergestellt aus tschechischer ger\u00f6steter BIO Gerste. Tsampa gilt als eigenst\u00e4ndiges Superfood mit hohem N\u00e4hrwert. Tsampa ist reich an komplexen Kohlenhydraten, Ballaststoffen, Proteinen, gesunden Fetten, Vitaminen und Mineralien. Dies macht es zu einem Lebensmittel, das reich an N\u00e4hrstoffen ist, welches eine gro\u00dfz\u00fcgige Portion Energie liefert und K\u00f6rper und Geist unterst\u00fctzt. Der Dalai Lama und viele Menschen auf der ganzen Welt genie\u00dfen Tsampa regelm\u00e4\u00dfig. Schlie\u00df dich ihnen an \ud83d\ude42<\/p>\n<ul>\n<li>ICH BIN NICHT SOFORTIG<\/li>\n<li>N\u00dcTZLICHE BETA-GLUCANE<\/li>\n<li>VIELE MINERALSTOFFE UND VITAMINE<\/li>\n<li>HOHER PROTEINGEHALT<\/li>\n<\/ul>\n","protected":false},"featured_media":3970,"template":"","meta":{"inline_featured_image":false},"product-attribute":[411,512,413,415],"product_cat":[202,203],"product_tag":[],"class_list":{"0":"post-2943","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product-attribute-organic-de","7":"product-attribute-prufen","8":"product-attribute-vegan-de","9":"product-attribute-vegetarian-de","10":"product_cat-alle-produkte","11":"product_cat-foods-ernahrung","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TSAMPA ORIGINAL BIO 250g, 650G - BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TSAMPA ORIGINAL BIO 250g, 650G - BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE\" \/>\n<meta property=\"og:description\" content=\"Barlee&#039;s bringt Ihnen die m\u00e4chtige Kraft von Tsampa. Tsampa ist ein traditionelles tibetisches Essen, bei uns hergestellt aus tschechischer ger\u00f6steter BIO Gerste. Tsampa gilt als eigenst\u00e4ndiges Superfood mit hohem N\u00e4hrwert. Tsampa ist reich an komplexen Kohlenhydraten, Ballaststoffen, Proteinen, gesunden Fetten, Vitaminen und Mineralien. Dies macht es zu einem Lebensmittel, das reich an N\u00e4hrstoffen ist, welches eine gro\u00dfz\u00fcgige Portion Energie liefert und K\u00f6rper und Geist unterst\u00fctzt. Der Dalai Lama und viele Menschen auf der ganzen Welt genie\u00dfen Tsampa regelm\u00e4\u00dfig. Schlie\u00df dich ihnen an :)  ICH BIN NICHT SOFORTIG  N\u00dcTZLICHE BETA-GLUCANE  VIELE MINERALSTOFFE UND VITAMINE  HOHER PROTEINGEHALT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/\" \/>\n<meta property=\"og:site_name\" content=\"BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-21T17:07:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/barlees_tsampa_250g1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/\",\"url\":\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/\",\"name\":\"TSAMPA ORIGINAL BIO 250g, 650G - BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE\",\"isPartOf\":{\"@id\":\"https:\/\/barlees.eu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/barlees_tsampa_250g1.jpg\",\"datePublished\":\"2023-04-18T19:02:06+00:00\",\"dateModified\":\"2026-06-21T17:07:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#primaryimage\",\"url\":\"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/barlees_tsampa_250g1.jpg\",\"contentUrl\":\"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/barlees_tsampa_250g1.jpg\",\"width\":1000,\"height\":1498,\"caption\":\"tsampa 250g\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\/\/barlees.eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/barlees.eu\/de\/eshop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TSAMPA ORIGINAL BIO 250g, 650G\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/barlees.eu\/de\/#website\",\"url\":\"https:\/\/barlees.eu\/de\/\",\"name\":\"BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE\",\"description\":\"BARLEE\u00b4S V\u00c1M P\u0158IN\u00c1\u0160\u00cd JEDINE\u010cN\u00c9 PRODUKTY Z JE\u010cMENE\",\"publisher\":{\"@id\":\"https:\/\/barlees.eu\/de\/#organization\"},\"alternateName\":\"BARLEE\u00b4S\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/barlees.eu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/barlees.eu\/de\/#organization\",\"name\":\"BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE\",\"url\":\"https:\/\/barlees.eu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/barlees.eu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/cropped-barlees_panacek_cerny.png\",\"contentUrl\":\"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/cropped-barlees_panacek_cerny.png\",\"width\":512,\"height\":512,\"caption\":\"BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE\"},\"image\":{\"@id\":\"https:\/\/barlees.eu\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TSAMPA ORIGINAL BIO 250g, 650G - BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/","og_locale":"de_DE","og_type":"article","og_title":"TSAMPA ORIGINAL BIO 250g, 650G - BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE","og_description":"Barlee's bringt Ihnen die m\u00e4chtige Kraft von Tsampa. Tsampa ist ein traditionelles tibetisches Essen, bei uns hergestellt aus tschechischer ger\u00f6steter BIO Gerste. Tsampa gilt als eigenst\u00e4ndiges Superfood mit hohem N\u00e4hrwert. Tsampa ist reich an komplexen Kohlenhydraten, Ballaststoffen, Proteinen, gesunden Fetten, Vitaminen und Mineralien. Dies macht es zu einem Lebensmittel, das reich an N\u00e4hrstoffen ist, welches eine gro\u00dfz\u00fcgige Portion Energie liefert und K\u00f6rper und Geist unterst\u00fctzt. Der Dalai Lama und viele Menschen auf der ganzen Welt genie\u00dfen Tsampa regelm\u00e4\u00dfig. Schlie\u00df dich ihnen an :)  ICH BIN NICHT SOFORTIG  N\u00dcTZLICHE BETA-GLUCANE  VIELE MINERALSTOFFE UND VITAMINE  HOHER PROTEINGEHALT","og_url":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/","og_site_name":"BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE","article_modified_time":"2026-06-21T17:07:08+00:00","og_image":[{"width":1000,"height":1498,"url":"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/barlees_tsampa_250g1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/","url":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/","name":"TSAMPA ORIGINAL BIO 250g, 650G - BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE","isPartOf":{"@id":"https:\/\/barlees.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#primaryimage"},"image":{"@id":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#primaryimage"},"thumbnailUrl":"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/barlees_tsampa_250g1.jpg","datePublished":"2023-04-18T19:02:06+00:00","dateModified":"2026-06-21T17:07:08+00:00","breadcrumb":{"@id":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#primaryimage","url":"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/barlees_tsampa_250g1.jpg","contentUrl":"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/barlees_tsampa_250g1.jpg","width":1000,"height":1498,"caption":"tsampa 250g"},{"@type":"BreadcrumbList","@id":"https:\/\/barlees.eu\/de\/produkt\/tsampa-original-bio-250g-650g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/barlees.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/barlees.eu\/de\/eshop\/"},{"@type":"ListItem","position":3,"name":"TSAMPA ORIGINAL BIO 250g, 650G"}]},{"@type":"WebSite","@id":"https:\/\/barlees.eu\/de\/#website","url":"https:\/\/barlees.eu\/de\/","name":"BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE","description":"BARLEE\u00b4S V\u00c1M P\u0158IN\u00c1\u0160\u00cd JEDINE\u010cN\u00c9 PRODUKTY Z JE\u010cMENE","publisher":{"@id":"https:\/\/barlees.eu\/de\/#organization"},"alternateName":"BARLEE\u00b4S","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barlees.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/barlees.eu\/de\/#organization","name":"BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE","url":"https:\/\/barlees.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/barlees.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/cropped-barlees_panacek_cerny.png","contentUrl":"https:\/\/barlees.eu\/wp-content\/uploads\/2023\/04\/cropped-barlees_panacek_cerny.png","width":512,"height":512,"caption":"BARLEE\u00b4S - MOCN\u00c1 S\u00cdLA JE\u010cMENE"},"image":{"@id":"https:\/\/barlees.eu\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/barlees.eu\/de\/wp-json\/wp\/v2\/product\/2943"}],"collection":[{"href":"https:\/\/barlees.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/barlees.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/barlees.eu\/de\/wp-json\/wp\/v2\/media\/3970"}],"wp:attachment":[{"href":"https:\/\/barlees.eu\/de\/wp-json\/wp\/v2\/media?parent=2943"}],"wp:term":[{"taxonomy":"product-attribute","embeddable":true,"href":"https:\/\/barlees.eu\/de\/wp-json\/wp\/v2\/product-attribute?post=2943"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/barlees.eu\/de\/wp-json\/wp\/v2\/product_cat?post=2943"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/barlees.eu\/de\/wp-json\/wp\/v2\/product_tag?post=2943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}